{"id":179,"count":2,"description":"","link":"https:\/\/thequaintkitchen.com\/en\/tag\/corn\/","name":"Corn","slug":"corn","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Corn Archives - The Quaint Kitchen<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/thequaintkitchen.com\/en\/tag\/corn\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Corn Archives - The Quaint Kitchen\" \/>\n<meta property=\"og:url\" content=\"https:\/\/thequaintkitchen.com\/en\/tag\/corn\/\" \/>\n<meta property=\"og:site_name\" content=\"The Quaint Kitchen\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/thequaintkitchen.com\\\/tag\\\/corn\\\/\",\"url\":\"https:\\\/\\\/thequaintkitchen.com\\\/tag\\\/corn\\\/\",\"name\":\"Corn Archives - The Quaint Kitchen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/thequaintkitchen.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/thequaintkitchen.com\\\/tag\\\/corn\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/thequaintkitchen.com\\\/tag\\\/corn\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/thequaintkitchen.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Corn\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/thequaintkitchen.com\\\/#website\",\"url\":\"https:\\\/\\\/thequaintkitchen.com\\\/\",\"name\":\"The Quaint Kitchen\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/thequaintkitchen.com\\\/#\\\/schema\\\/person\\\/6f96d9f1b03bd73e315534a31a1fc193\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/thequaintkitchen.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/thequaintkitchen.com\\\/#\\\/schema\\\/person\\\/6f96d9f1b03bd73e315534a31a1fc193\",\"name\":\"Tatyana\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/thequaintkitchen.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/Q.png\",\"url\":\"https:\\\/\\\/thequaintkitchen.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/Q.png\",\"contentUrl\":\"https:\\\/\\\/thequaintkitchen.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/Q.png\",\"width\":512,\"height\":512,\"caption\":\"Tatyana\"},\"logo\":{\"@id\":\"https:\\\/\\\/thequaintkitchen.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/Q.png\"},\"sameAs\":[\"https:\\\/\\\/thequaintkitchen.com\",\"https:\\\/\\\/www.instagram.com\\\/the.quaint.kitchen\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Corn Archives - The Quaint Kitchen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/thequaintkitchen.com\/en\/tag\/corn\/","og_locale":"en_US","og_type":"article","og_title":"Corn Archives - The Quaint Kitchen","og_url":"https:\/\/thequaintkitchen.com\/en\/tag\/corn\/","og_site_name":"The Quaint Kitchen","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/thequaintkitchen.com\/tag\/corn\/","url":"https:\/\/thequaintkitchen.com\/tag\/corn\/","name":"Corn Archives - The Quaint Kitchen","isPartOf":{"@id":"https:\/\/thequaintkitchen.com\/#website"},"breadcrumb":{"@id":"https:\/\/thequaintkitchen.com\/tag\/corn\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/thequaintkitchen.com\/tag\/corn\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/thequaintkitchen.com\/"},{"@type":"ListItem","position":2,"name":"Corn"}]},{"@type":"WebSite","@id":"https:\/\/thequaintkitchen.com\/#website","url":"https:\/\/thequaintkitchen.com\/","name":"The Quaint Kitchen","description":"","publisher":{"@id":"https:\/\/thequaintkitchen.com\/#\/schema\/person\/6f96d9f1b03bd73e315534a31a1fc193"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/thequaintkitchen.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/thequaintkitchen.com\/#\/schema\/person\/6f96d9f1b03bd73e315534a31a1fc193","name":"Tatyana","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/thequaintkitchen.com\/wp-content\/uploads\/2020\/07\/Q.png","url":"https:\/\/thequaintkitchen.com\/wp-content\/uploads\/2020\/07\/Q.png","contentUrl":"https:\/\/thequaintkitchen.com\/wp-content\/uploads\/2020\/07\/Q.png","width":512,"height":512,"caption":"Tatyana"},"logo":{"@id":"https:\/\/thequaintkitchen.com\/wp-content\/uploads\/2020\/07\/Q.png"},"sameAs":["https:\/\/thequaintkitchen.com","https:\/\/www.instagram.com\/the.quaint.kitchen\/"]}]}},"_links":{"self":[{"href":"https:\/\/thequaintkitchen.com\/en\/wp-json\/wp\/v2\/tags\/179","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/thequaintkitchen.com\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/thequaintkitchen.com\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/thequaintkitchen.com\/en\/wp-json\/wp\/v2\/posts?tags=179"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}